{"id":6354,"date":"2023-03-25T16:49:22","date_gmt":"2023-03-25T12:49:22","guid":{"rendered":"https:\/\/silkaccess.ge\/?p=6354"},"modified":"2023-04-04T13:01:00","modified_gmt":"2023-04-04T09:01:00","slug":"chinuri-ar-nishnavs-tsuds","status":"publish","type":"post","link":"https:\/\/silkaccess.ge\/zh\/chinuri-ar-nishnavs-tsuds\/","title":{"rendered":"\u201c\u4e2d\u56fd\u5236\u9020\u201d\u5e76\u4e0d\u4ee3\u8868\u4e0d\u597d"},"content":{"rendered":"<p><\/p>\n<p>\u6211\u4eec\u5f88\u9ad8\u5174\u5730\u5ba3\u5e03\u6211\u4eec\u7684\u65b0\u6d3b\u52a8\uff0c\u201c\u4e2d\u56fd\u5236\u9020\u5e76\u4e0d\u610f\u5473\u7740\u4e0d\u597d\u201d\u3002 \u6211\u4eec\u8ba4\u4e3a\u5b58\u5728\u4e2d\u56fd\u4ea7\u54c1\u8d28\u91cf\u4f4e\u4e0b\u7684\u523b\u677f\u5370\u8c61\uff0c\u4f46\u6211\u4eec\u4ece\u7ecf\u9a8c\u4e2d\u77e5\u9053\u8fd9\u4e0d\u662f\u771f\u7684\u3002 \u4f5c\u4e3a\u4e00\u5bb6\u8fdb\u51fa\u53e3\u516c\u53f8\uff0c\u6211\u4eec\u4e0e\u8bb8\u591a\u4e2d\u56fd\u5236\u9020\u5546\u5408\u4f5c\uff0c\u53d1\u73b0\u4ed6\u4eec\u7684\u4ea7\u54c1\u901a\u5e38\u8d28\u91cf\u4e0a\u4e58\uff0c\u7269\u8d85\u6240\u503c\u3002<\/p>\n<p>\u6211\u4eec\u60f3\u6253\u7834\u8fd9\u79cd\u523b\u677f\u5370\u8c61\uff0c\u8ba9\u4eba\u4eec\u4e86\u89e3\u4e2d\u56fd\u5236\u9020\u7684\u4ea7\u54c1\u8d28\u91cf\u3002 \u6211\u4eec\u7684\u76ee\u6807\u662f\u5e2e\u52a9\u4eba\u4eec\u505a\u51fa\u660e\u667a\u7684\u9009\u62e9\u5e76\u4fc3\u8fdb\u516c\u5e73\u8d38\u6613\u5b9e\u8df5\u3002<\/p>\n<p>\u52a0\u5165\u6211\u4eec\u7684\u6d3b\u52a8\uff0c\u8ba9\u6211\u4eec\u4e00\u8d77\u52aa\u529b\u6539\u53d8\u5bf9\u4e2d\u56fd\u5236\u9020\u4ea7\u54c1\u7684\u770b\u6cd5\u3002 \u6211\u4eec\u53ef\u4ee5\u5171\u540c\u5e2e\u52a9\u652f\u6301\u4e2d\u56fd\u7684\u4f01\u4e1a\uff0c\u5e76\u5728\u4e16\u754c\u8303\u56f4\u5185\u63a8\u5e7f\u4f18\u8d28\u4ea7\u54c1\u3002<\/p>\n<style>\/*! elementor - v3.12.0 - 29-03-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>\u6211\u4eec\u5f88\u9ad8\u5174\u5730\u5ba3\u5e03\u6211\u4eec\u7684\u65b0\u6d3b\u52a8\uff0c\u201c\u4e2d\u56fd\u5236\u9020\u5e76\u4e0d\u610f\u5473\u7740\u4e0d\u597d\u201d\u3002 \u6211\u4eec\u8ba4\u4e3a\u5b58\u5728\u4e2d\u56fd\u4ea7\u54c1\u8d28\u91cf\u4f4e\u4e0b\u7684\u523b\u677f\u5370\u8c61\uff0c\u4f46\u6211\u4eec\u4ece\u7ecf [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[73,74],"class_list":["post-6354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-china","tag-china","tag-chinuri-ar-nishnavs-tsuds"],"_links":{"self":[{"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/posts\/6354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/comments?post=6354"}],"version-history":[{"count":14,"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/posts\/6354\/revisions"}],"predecessor-version":[{"id":6404,"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/posts\/6354\/revisions\/6404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/media\/6355"}],"wp:attachment":[{"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/media?parent=6354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/categories?post=6354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/silkaccess.ge\/zh\/wp-json\/wp\/v2\/tags?post=6354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}